{"id":24,"date":"2023-08-18T13:35:11","date_gmt":"2023-08-18T13:35:11","guid":{"rendered":"https:\/\/talkto.ac\/?page_id=24"},"modified":"2026-03-21T06:24:05","modified_gmt":"2026-03-21T06:24:05","slug":"a-propos","status":"publish","type":"page","link":"https:\/\/talkto.ac\/pt\/a-propos\/","title":{"rendered":"Sobre n\u00f3s"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;About&#8221; module_class=&#8221;about&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px||0px||true|false&#8221; custom_padding=&#8221;0px||50px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;default&#8221; width=&#8221;60%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text module_class=&#8221;custom-title&#8221; _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>A empresa<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Os nossos valores baseiam-se na qualidade, na exatid\u00e3o e na confian\u00e7a. Cada um dos nossos testes de l\u00ednguas \u00e9 cuidadosamente concebido por uma equipa de peritos lingu\u00edsticos qualificados. Asseguramos que os nossos testes proporcionam uma avalia\u00e7\u00e3o exaustiva das diferentes compet\u00eancias lingu\u00edsticas:<\/p>\n<ul>\n<li><span>Compreens\u00e3o escrita<\/span><\/li>\n<li><span>Compreens\u00e3o oral<\/span><\/li>\n<li><span>Gram\u00e1tica<\/span><\/li>\n<li><span>Vocabul\u00e1rio<\/span><\/li>\n<li><span>Express\u00e3o escrita<\/span><\/li>\n<\/ul>\n<p>Pode ter a certeza de que os resultados dos nossos testes reflectem com exatid\u00e3o o seu n\u00edvel lingu\u00edstico atual.<br \/>Todas as informa\u00e7\u00f5es fornecidas durante os testes s\u00e3o estritamente confidenciais e s\u00f3 s\u00e3o utilizadas para avaliar o seu n\u00edvel lingu\u00edstico.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Projet&#8221; _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#e2f8fd&#8221; custom_margin=&#8221;0px||||false|false&#8221; custom_padding=&#8221;20px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;default&#8221; width=&#8221;60%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text module_class=&#8221;custom-title white&#8221; _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>O projeto<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Compreender as subtilezas da l\u00edngua vai al\u00e9m da simples memoriza\u00e7\u00e3o de palavras. Reflecte uma mente aberta, curiosidade intelectual e um desejo cont\u00ednuo de explorar e aprender. \u00c9 a chave para compreender como funciona o ambiente empresarial internacional, entender os diferentes comportamentos lingu\u00edsticos e adotar novas perspectivas.<\/p>\n<p>Em suma, a flu\u00eancia \u00e9 uma vantagem que pode ser desenvolvida em qualquer altura, oferecendo uma fonte constante de aprendizagem e de est\u00edmulo intelectual. Comprometa-se a avaliar a sua compreens\u00e3o e a melhorar as suas compet\u00eancias lingu\u00edsticas!<\/p>\n<p>A compreens\u00e3o de vai para al\u00e9m da simples acumula\u00e7\u00e3o de factos. Incorpora uma mente aberta, curiosidade intelectual e uma sede constante de descoberta.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;About test&#8221; module_class=&#8221;about-test&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px||0px||true|false&#8221; custom_padding=&#8221;0px||50px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;default&#8221; width=&#8221;60%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text module_class=&#8221;custom-title&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Os testes<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;10px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Cada question\u00e1rio \u00e9 gerado aleatoriamente a partir de uma base de dados de perguntas. Esta abordagem garante uma diversidade consider\u00e1vel nas avalia\u00e7\u00f5es e assegura uma experi\u00eancia de aprendizagem \u00f3ptima. Estas avalia\u00e7\u00f5es aleat\u00f3rias e imparciais s\u00e3o acess\u00edveis a todos os nossos utilizadores, quer sejam novos ou experientes na prepara\u00e7\u00e3o para exames.<\/p>\n<p>Apesar das varia\u00e7\u00f5es de dificuldade entre as perguntas, cada teste foi concebido para manter um n\u00edvel de dificuldade uniforme. Isto garante uma avalia\u00e7\u00e3o justa para cada utilizador, independentemente do seu n\u00edvel de profici\u00eancia lingu\u00edstica.<\/p>\n<p>O nosso teste consiste em 18 perguntas divididas em duas categorias distintas: compreens\u00e3o de leitura e compreens\u00e3o oral. As perguntas s\u00e3o geradas aleatoriamente.<\/p>\n<p>Tamb\u00e9m oferecemos testes premium com um maior n\u00famero de perguntas, dispon\u00edveis para os nossos subscritores. Estes testes permitem-lhe praticar com mais precis\u00e3o e com uma grande variedade de perguntas.<\/p>\n<p>As nossas avalia\u00e7\u00f5es s\u00e3o concebidas para serem justas e diversificadas, promovendo o desenvolvimento efetivo e agrad\u00e1vel das compet\u00eancias lingu\u00edsticas.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/talkto.ac\/wp-content\/uploads\/2023\/08\/About_Test.svg&#8221; title_text=&#8221;About_Test&#8221; _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;default&#8221; positioning=&#8221;relative&#8221; horizontal_offset_tablet=&#8221;&#8221; horizontal_offset_phone=&#8221;15vw&#8221; horizontal_offset_last_edited=&#8221;on|phone&#8221; width_tablet=&#8221;&#8221; width_phone=&#8221;300px&#8221; width_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;default&#8221; width=&#8221;60%&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/talkto.ac\/wp-content\/uploads\/2023\/08\/About_Confirme.svg&#8221; title_text=&#8221;About_Confirm\u00e9&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||20px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|700|||||||&#8221; text_text_color=&#8221;#173f56&#8243; text_font_size=&#8221;20px&#8221; text_orientation=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Numerosos testes m\u00f3veis<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/talkto.ac\/wp-content\/uploads\/2023\/08\/About_Performance.svg&#8221; title_text=&#8221;About_Performance&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||20px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|700|||||||&#8221; text_text_color=&#8221;#173f56&#8243; text_font_size=&#8221;20px&#8221; text_orientation=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Respostas corrigidas para o ajudar a progredir<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/talkto.ac\/wp-content\/uploads\/2023\/08\/About_Confiance.svg&#8221; title_text=&#8221;About_Confiance&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||20px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|700|||||||&#8221; text_text_color=&#8221;#173f56&#8243; text_font_size=&#8221;20px&#8221; text_orientation=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Testes mais avan\u00e7ados para subscritores<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Results&#8221; module_class=&#8221;custom-tests&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px||0px||true|false&#8221; custom_padding=&#8221;0px||50px||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text module_class=&#8221;custom-title&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; header_4_font=&#8221;|300|||||||&#8221; header_4_text_align=&#8221;center&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Os nossos testes premium est\u00e3o inclu\u00eddos na subscri\u00e7\u00e3o<\/h2>\n<p>&nbsp;<\/p>\n<h4><span>Estes testes s\u00e3o reservados exclusivamente aos assinantes premium e podem ser acedidos a partir da sua \u00e1rea \"A minha conta\".<\/span><\/h4>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; make_equal=&#8221;on&#8221; module_class=&#8221;list-premiums&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;60%&#8221; width_tablet=&#8221;60%&#8221; width_phone=&#8221;80%&#8221; width_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; module_class=&#8221;card-premium 30quest&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;30px|30px|30px|30px|true|true&#8221; border_radii=&#8221;on|30px|30px|30px|30px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_horizontal=&#8221;5px&#8221; box_shadow_vertical=&#8221;5px&#8221; box_shadow_blur=&#8221;15px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.16)&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/talkto.ac\/wp-content\/uploads\/2023\/08\/About_Confiance.svg&#8221; title_text=&#8221;About_Confiance&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;70%&#8221; module_alignment=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text module_class=&#8221;tarif-desc&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;16px&#8221; header_3_font=&#8221;|700|||||||&#8221; header_3_text_color=&#8221;#173f56&#8243; text_orientation=&#8221;center&#8221; width=&#8221;100%&#8221; module_alignment=&#8221;center&#8221; min_height=&#8221;150px&#8221; text_font_size_tablet=&#8221;16px&#8221; text_font_size_phone=&#8221;16px&#8221; text_font_size_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Teste de ingl\u00eas - 30 perguntas<\/h3>\n<p><span>Descubra o seu dom\u00ednio da l\u00edngua inglesa com o nosso teste conciso de 30 perguntas. Avalie as nuances do seu n\u00edvel em apenas alguns minutos gra\u00e7as a esta explora\u00e7\u00e3o aprofundada.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; module_class=&#8221;card-premium 60quest&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;30px|30px|30px|30px|true|true&#8221; border_radii=&#8221;on|30px|30px|30px|30px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_horizontal=&#8221;5px&#8221; box_shadow_vertical=&#8221;5px&#8221; box_shadow_blur=&#8221;15px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.16)&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/talkto.ac\/wp-content\/uploads\/2023\/08\/Etape04.svg&#8221; title_text=&#8221;Etape04&#8243; align=&#8221;center&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;70%&#8221; module_alignment=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text module_class=&#8221;tarif-desc&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;16px&#8221; header_3_font=&#8221;|700|||||||&#8221; header_3_text_color=&#8221;#173f56&#8243; text_orientation=&#8221;center&#8221; width=&#8221;100%&#8221; module_alignment=&#8221;center&#8221; min_height=&#8221;150px&#8221; text_font_size_tablet=&#8221;16px&#8221; text_font_size_phone=&#8221;16px&#8221; text_font_size_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Teste de ingl\u00eas - 60 perguntas<\/h3>\n<p><span>Descubra o seu dom\u00ednio da l\u00edngua inglesa com o nosso teste pormenorizado de 60 perguntas. Avalie as nuances do seu n\u00edvel em apenas alguns minutos gra\u00e7as a esta explora\u00e7\u00e3o aprofundada.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; module_class=&#8221;card-premium 90quest&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;30px|30px|30px|30px|true|true&#8221; border_radii=&#8221;on|30px|30px|30px|30px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_horizontal=&#8221;5px&#8221; box_shadow_vertical=&#8221;5px&#8221; box_shadow_blur=&#8221;15px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.16)&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/talkto.ac\/wp-content\/uploads\/2023\/08\/Etape03.svg&#8221; title_text=&#8221;Etape03&#8243; align=&#8221;center&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;70%&#8221; module_alignment=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text module_class=&#8221;tarif-desc&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;16px&#8221; header_3_font=&#8221;|700|||||||&#8221; header_3_text_color=&#8221;#173f56&#8243; text_orientation=&#8221;center&#8221; width=&#8221;100%&#8221; module_alignment=&#8221;center&#8221; min_height=&#8221;150px&#8221; text_font_size_tablet=&#8221;16px&#8221; text_font_size_phone=&#8221;16px&#8221; text_font_size_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Teste de ingl\u00eas - 90 perguntas<\/h3>\n<p><span>Descubra o seu dom\u00ednio da l\u00edngua inglesa com o nosso teste exaustivo de 90 perguntas. Teste as subtilezas das suas compet\u00eancias lingu\u00edsticas em apenas alguns minutos com esta explora\u00e7\u00e3o aprofundada.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; make_equal=&#8221;on&#8221; module_class=&#8221;list-premiums&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;60%&#8221; width_tablet=&#8221;60%&#8221; width_phone=&#8221;80%&#8221; width_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; module_class=&#8221;card-premium 120quest&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;30px|30px|30px|30px|true|true&#8221; border_radii=&#8221;on|30px|30px|30px|30px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_horizontal=&#8221;5px&#8221; box_shadow_vertical=&#8221;5px&#8221; box_shadow_blur=&#8221;15px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.16)&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/talkto.ac\/wp-content\/uploads\/2023\/08\/About_Confirme.svg&#8221; title_text=&#8221;About_Confirm\u00e9&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;70%&#8221; module_alignment=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text module_class=&#8221;tarif-desc&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;16px&#8221; header_3_font=&#8221;|700|||||||&#8221; header_3_text_color=&#8221;#173f56&#8243; text_orientation=&#8221;center&#8221; width=&#8221;100%&#8221; module_alignment=&#8221;center&#8221; min_height=&#8221;150px&#8221; text_font_size_tablet=&#8221;16px&#8221; text_font_size_phone=&#8221;16px&#8221; text_font_size_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Teste de Ingl\u00eas - 120 perguntas<\/h3>\n<p><span>Descubra o seu dom\u00ednio da l\u00edngua inglesa com o nosso teste exaustivo de 120 perguntas. Avalie as nuances do seu n\u00edvel em apenas alguns minutos gra\u00e7as a esta explora\u00e7\u00e3o pormenorizada.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; module_class=&#8221;card-premium 150quest&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;30px|30px|30px|30px|true|true&#8221; border_radii=&#8221;on|30px|30px|30px|30px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_horizontal=&#8221;5px&#8221; box_shadow_vertical=&#8221;5px&#8221; box_shadow_blur=&#8221;15px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.16)&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/talkto.ac\/wp-content\/uploads\/2023\/08\/About_Performance.svg&#8221; title_text=&#8221;About_Performance&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;70%&#8221; module_alignment=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text module_class=&#8221;tarif-desc&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;16px&#8221; header_3_font=&#8221;|700|||||||&#8221; header_3_text_color=&#8221;#173f56&#8243; text_orientation=&#8221;center&#8221; width=&#8221;100%&#8221; module_alignment=&#8221;center&#8221; min_height=&#8221;150px&#8221; text_font_size_tablet=&#8221;16px&#8221; text_font_size_phone=&#8221;16px&#8221; text_font_size_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Teste de ingl\u00eas - 150 perguntas<\/h3>\n<p><span>Descubra o seu dom\u00ednio da l\u00edngua inglesa com o nosso teste exaustivo de 150 perguntas. Avalie as subtilezas das suas compet\u00eancias lingu\u00edsticas em apenas alguns minutos com esta explora\u00e7\u00e3o exaustiva.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; module_class=&#8221;card-premium 180quest&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;30px|30px|30px|30px|true|true&#8221; border_radii=&#8221;on|30px|30px|30px|30px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_horizontal=&#8221;5px&#8221; box_shadow_vertical=&#8221;5px&#8221; box_shadow_blur=&#8221;15px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.16)&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/talkto.ac\/wp-content\/uploads\/2023\/08\/About_Test.svg&#8221; title_text=&#8221;About_Test&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;70%&#8221; module_alignment=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text module_class=&#8221;tarif-desc&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;16px&#8221; header_3_font=&#8221;|700|||||||&#8221; header_3_text_color=&#8221;#173f56&#8243; text_orientation=&#8221;center&#8221; width=&#8221;100%&#8221; module_alignment=&#8221;center&#8221; min_height=&#8221;150px&#8221; text_font_size_tablet=&#8221;16px&#8221; text_font_size_phone=&#8221;16px&#8221; text_font_size_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Teste de ingl\u00eas - 180 perguntas<\/h3>\n<p><span>Descubra o seu dom\u00ednio da l\u00edngua inglesa com o nosso teste mais completo de 180 perguntas. Avalie as nuances do seu n\u00edvel em apenas alguns minutos gra\u00e7as a esta explora\u00e7\u00e3o exaustiva.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; admin_label=&#8221;Testimonials&#8221; module_class=&#8221;custom-testi&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px||0px||true|false&#8221; custom_padding=&#8221;0px||120px||false|false&#8221; custom_padding_tablet=&#8221;||100px||false|false&#8221; custom_padding_phone=&#8221;||100px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text module_class=&#8221;custom-title&#8221; _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Coment\u00e1rios<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; module_class=&#8221;testi-row&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px||0px||false|true&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; background_enable_image=&#8221;off&#8221; custom_padding=&#8221;20px||20px||true|true&#8221; border_radii=&#8221;on|30px|30px|30px|30px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_color=&#8221;rgba(0,0,0,0.16)&#8221; global_colors_info=&#8221;{}&#8221; custom_css_before_last_edited=&#8221;on|phone&#8221; custom_css_main_element_last_edited=&#8221;on|tablet&#8221; custom_css_main_element_tablet=&#8221;margin-top:4vh;||margin-bottom:10vh;&#8221; custom_css_main_element_phone=&#8221;margin-top:4vh;||margin-bottom:10vh;&#8221;][et_pb_text module_class=&#8221;full&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; header_5_font=&#8221;|700|||||||&#8221; header_5_font_size=&#8221;22px&#8221; background_enable_image=&#8221;off&#8221; background_size=&#8221;stretch&#8221; width=&#8221;80%&#8221; width_tablet=&#8221;80%&#8221; width_phone=&#8221;100%&#8221; width_last_edited=&#8221;on|tablet&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||||true|false&#8221; custom_padding=&#8221;||||true|true&#8221; custom_padding_tablet=&#8221;|50px||50px|true|true&#8221; custom_padding_phone=&#8221;0px|20px|0px|20px|true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; header_5_font_size_tablet=&#8221;22px&#8221; header_5_font_size_phone=&#8221;20px&#8221; header_5_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<div class=\"testimonial\">\n<div class=\"header-testi\">\n<p><img decoding=\"async\" src=\"https:\/\/talkto.ac\/wp-content\/uploads\/2023\/08\/Jeanne.svg\" width=\"68\" height=\"68\" alt=\"\" class=\"wp-image-390 alignleft size-full\" \/><\/p>\n<h5>Ana\u00efs, 26 anos<\/h5>\n<\/div>\n<p>\"Um teste s\u00e9rio e completo, que me permitiu testar os meus progressos.\"<\/p>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; background_enable_image=&#8221;off&#8221; vertical_offset_tablet=&#8221;&#8221; vertical_offset_phone=&#8221;&#8221; vertical_offset_last_edited=&#8221;on|desktop&#8221; position_origin_a_tablet=&#8221;&#8221; position_origin_a_phone=&#8221;&#8221; position_origin_a_last_edited=&#8221;on|desktop&#8221; position_origin_f_tablet=&#8221;&#8221; position_origin_f_phone=&#8221;&#8221; position_origin_f_last_edited=&#8221;on|desktop&#8221; position_origin_r_tablet=&#8221;&#8221; position_origin_r_phone=&#8221;&#8221; position_origin_r_last_edited=&#8221;on|desktop&#8221; custom_padding=&#8221;20px||20px||true|true&#8221; positioning_tablet=&#8221;&#8221; positioning_phone=&#8221;&#8221; positioning_last_edited=&#8221;on|desktop&#8221; custom_css_main_element=&#8221;margin-top:100px;&#8221; border_radii=&#8221;on|30px|30px|30px|30px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_color=&#8221;rgba(0,0,0,0.16)&#8221; global_colors_info=&#8221;{}&#8221; custom_css_before_last_edited=&#8221;on|desktop&#8221; custom_css_main_element_last_edited=&#8221;on|tablet&#8221; custom_css_main_element_tablet=&#8221;margin-top:4vh;||margin-bottom:10vh;&#8221; custom_css_main_element_phone=&#8221;margin-top:4vh;||margin-bottom:10vh;&#8221;][et_pb_text module_class=&#8221;full&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; header_5_font=&#8221;|700|||||||&#8221; header_5_font_size=&#8221;22px&#8221; background_enable_image=&#8221;off&#8221; background_size=&#8221;stretch&#8221; positioning=&#8221;relative&#8221; width=&#8221;80%&#8221; width_tablet=&#8221;80%&#8221; width_phone=&#8221;100%&#8221; width_last_edited=&#8221;on|phone&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||||true|false&#8221; custom_padding=&#8221;||||true|true&#8221; custom_padding_tablet=&#8221;|50px||50px|true|true&#8221; custom_padding_phone=&#8221;0px|20px|0px|20px|true|true&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; header_5_font_size_tablet=&#8221;22px&#8221; header_5_font_size_phone=&#8221;20px&#8221; header_5_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<div class=\"testimonial\">\n<div class=\"header-testi\">\n<p><img decoding=\"async\" src=\"https:\/\/talkto.ac\/wp-content\/uploads\/2023\/08\/Nicolas.svg\" width=\"68\" height=\"68\" alt=\"\" class=\"wp-image-391 alignleft size-full\" \/><\/p>\n<h5>Pierre, 37 anos<\/h5>\n<\/div>\n<p>\"Gosto da ideia de fazer este teste aos rec\u00e9m-chegados \u00e0 minha empresa\".<\/p>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; background_enable_image=&#8221;off&#8221; custom_padding=&#8221;20px||20px||true|true&#8221; border_radii=&#8221;on|30px|30px|30px|30px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_color=&#8221;rgba(0,0,0,0.16)&#8221; global_colors_info=&#8221;{}&#8221; custom_css_before_last_edited=&#8221;on|desktop&#8221; custom_css_main_element_last_edited=&#8221;on|tablet&#8221; custom_css_main_element_tablet=&#8221;margin-top:4vh;||margin-bottom:10vh;&#8221; custom_css_main_element_phone=&#8221;margin-top:4vh;||margin-bottom:10vh;&#8221;][et_pb_text module_class=&#8221;full&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; header_5_font=&#8221;|700|||||||&#8221; header_5_font_size=&#8221;22px&#8221; background_enable_image=&#8221;off&#8221; background_size=&#8221;stretch&#8221; width=&#8221;80%&#8221; width_tablet=&#8221;80%&#8221; width_phone=&#8221;100%&#8221; width_last_edited=&#8221;on|phone&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||||true|false&#8221; custom_padding=&#8221;||||true|true&#8221; custom_padding_tablet=&#8221;|50px||50px|true|true&#8221; custom_padding_phone=&#8221;0px|20px|0px|20px|true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; header_5_font_size_tablet=&#8221;22px&#8221; header_5_font_size_phone=&#8221;20px&#8221; header_5_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<div class=\"testimonial\">\n<div class=\"header-testi\">\n<p><img decoding=\"async\" src=\"https:\/\/talkto.ac\/wp-content\/uploads\/2023\/08\/Jessica.svg\" width=\"68\" height=\"68\" alt=\"\" class=\"wp-image-370 alignleft size-full\" \/><\/p>\n<h5>Cassie, 20 anos de idade<\/h5>\n<\/div>\n<p>\"Um teste qualificado que me deu uma ideia antes de fazer os exames\".<\/p>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px||||false|false&#8221; custom_padding=&#8221;0px||||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||40px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text module_class=&#8221;custom-title&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>As nossas tarifas<\/h2>\n<h4 class=\"text-sm md:text-[20px] font-normal text-[#353535] opacity-50 pt-[19px]\" style=\"text-align: center;\"><\/h4>\n<h4 class=\"text-sm md:text-[20px] font-normal text-[#353535] opacity-50 pt-[19px]\" style=\"text-align: center;\"><\/h4>\n<h4 class=\"text-sm md:text-[20px] font-normal text-[#353535] opacity-50 pt-[19px]\" style=\"text-align: center;\"><\/h4>\n<h3 class=\"text-sm md:text-[20px] font-normal text-[#353535] opacity-50 pt-[19px]\" style=\"text-align: center;\">Descubra as nossas tarifas adaptadas \u00e0s suas necessidades<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; make_equal=&#8221;on&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; module_class=&#8221;tarifs-block&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;60%&#8221; width_tablet=&#8221;70%&#8221; width_phone=&#8221;80%&#8221; width_last_edited=&#8221;on|tablet&#8221; custom_margin=&#8221;||||true&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; custom_padding_tablet=&#8221;0px||0px||true|true&#8221; custom_padding_phone=&#8221;0px||0px||true|true&#8221; border_radii=&#8221;on|5px|5px|5px|5px&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;rgba(0,0,0,0.15)&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#e2f8fd&#8221; custom_padding=&#8221;70px||70px||true|false&#8221; custom_padding_tablet=&#8221;70px|50px|70px|50px|true|true&#8221; custom_padding_phone=&#8221;|||40px|true|false&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text module_class=&#8221;tarif-title&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|700|||||||&#8221; text_text_color=&#8221;#173f56&#8243; text_font_size=&#8221;22px&#8221; text_orientation=&#8221;center&#8221; module_alignment=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Oferta experimental de 24 horas<\/p>\n<p>[\/et_pb_text][et_pb_text module_class=&#8221;tarif-price&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|600|||||||&#8221; text_text_color=&#8221;#ffb1b1&#8243; text_font_size=&#8221;35px&#8221; text_orientation=&#8221;center&#8221; width=&#8221;8vw&#8221; width_tablet=&#8221;20vw&#8221; width_phone=&#8221;40vw&#8221; width_last_edited=&#8221;on|tablet&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;||30px||false|false&#8221; border_width_bottom=&#8221;1px&#8221; border_color_bottom=&#8221;#ffb1b1&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>0.50 \u20ac<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|600|||||||&#8221; text_font_size=&#8221;25px&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;||15px||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]Puis <strong style=\"font-size: 30px;\"> 47.50 \u20ac<\/strong> \/Mois[\/et_pb_text][et_pb_text _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;15px&#8221; text_orientation=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p class=\"text-sm pb-2\">Ap\u00f3s 24 horas para um servi\u00e7o ilimitado. Cancelar em qualquer altura.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;30px||30px||true|false&#8221; custom_padding_tablet=&#8221;30px|50px|30px|50px|true|true&#8221; custom_padding_phone=&#8221;|40px||40px|true|true&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|600|||||||&#8221; text_font_size=&#8221;19px&#8221; text_line_height=&#8221;1.9em&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Explore estas funcionalidades ao subscrever este pacote tarif\u00e1rio<\/p>\n<p>[\/et_pb_text][et_pb_text module_class=&#8221;premium-list&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<ul>\n<li><span><strong>Acc\u00e8s <\/strong>\u00e0 notre vaste catalogue de <strong>livres \u00e9lectroniques.<\/strong><\/span><\/li>\n<li><span><strong>Acc\u00e8s illimit\u00e9<\/strong> \u00e0 tous les tests et outils d\u2019\u00e9valuation.<\/span><\/li>\n<li><span>Acc\u00e8s \u00e0 tout contenu futur suppl\u00e9mentaire qui sera t\u00e9l\u00e9charg\u00e9.<\/span><\/li>\n<li>Hist\u00f3rico completo dos seus resultados.<\/li>\n<li>Acess\u00edvel na Web, no telem\u00f3vel e no computador.<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;https:\/\/talkto.ac\/passer-le-test-1q\/&#8221; button_text=&#8221;Commencer le test&#8221; button_alignment=&#8221;center&#8221; disabled_on=&#8221;on|off|off&#8221; module_class=&#8221;custom-btn center&#8221; _builder_version=&#8221;4.27.4&#8243; _dynamic_attributes=&#8221;button_url&#8221; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||true|false&#8221; button_text_size_tablet=&#8221;&#8221; button_text_size_phone=&#8221;18px&#8221; button_text_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][et_pb_button button_url=&#8221;https:\/\/talkto.ac\/passer-le-test-1q\/&#8221; button_text=&#8221;Commencer&#8221; button_alignment=&#8221;center&#8221; disabled_on=&#8221;off|on|on&#8221; module_class=&#8221;custom-btn center&#8221; _builder_version=&#8221;4.27.4&#8243; _dynamic_attributes=&#8221;button_url&#8221; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||true|false&#8221; button_text_size_tablet=&#8221;&#8221; button_text_size_phone=&#8221;18px&#8221; button_text_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][et_pb_button button_url=&#8221;https:\/\/talkto.ac\/e-books\/&#8221; button_text=&#8221;D\u00e9couvrir nos e-books&#8221; button_alignment=&#8221;center&#8221; disabled_on=&#8221;off|off|off&#8221; module_class=&#8221; center&#8221; _builder_version=&#8221;4.27.4&#8243; _dynamic_attributes=&#8221;button_url&#8221; _module_preset=&#8221;default&#8221; button_bg_color=&#8221;#2191a8&#8243; custom_margin=&#8221;30px||||false|false&#8221; hover_enabled=&#8221;0&#8243; button_text_size_tablet=&#8221;&#8221; button_text_size_phone=&#8221;18px&#8221; button_text_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; module_class=&#8221;services-offer&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;50%&#8221; width_tablet=&#8221;50%&#8221; width_phone=&#8221;70%&#8221; width_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;|75px||75px|false|true&#8221; custom_padding_tablet=&#8221;|50px||50px|false|true&#8221; custom_padding_phone=&#8221;|50px||50px|false|true&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|600|||||||&#8221; text_font_size=&#8221;19px&#8221; custom_padding_tablet=&#8221;10px||||false|false&#8221; custom_padding_phone=&#8221;10px||||false|false&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; custom_css_before=&#8221;content:%22%22;||background:url(&#8216;https:\/\/talkto.ac\/wp-content\/uploads\/2024\/02\/shield-halved-solid-1.svg&#8217;);||background-repeat:no-repeat;||background-size:100%;||width:35px;||height:50px;||display:block;||position:absolute;||left:-50px;||top:15px;&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Garantia de reembolso de 14 dias<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;|95px||95px|false|true&#8221; custom_padding_tablet=&#8221;30px|50px||50px|false|true&#8221; custom_padding_phone=&#8221;30px|50px||50px|false|true&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; border_width_right=&#8221;2px&#8221; border_color_right=&#8221;rgba(186,186,186,0.29)&#8221; border_width_left=&#8221;2px&#8221; border_color_left=&#8221;rgba(186,186,186,0.29)&#8221; border_width_right_tablet=&#8221;0px&#8221; border_width_right_phone=&#8221;0px&#8221; border_width_right_last_edited=&#8221;on|tablet&#8221; border_width_left_tablet=&#8221;0px&#8221; border_width_left_phone=&#8221;0px&#8221; border_width_left_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|600|||||||&#8221; text_font_size=&#8221;19px&#8221; custom_padding_tablet=&#8221;10px||||false|false&#8221; custom_padding_phone=&#8221;10px||||false|false&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; custom_css_before=&#8221;content:%22%22;||background:url(&#8216;https:\/\/talkto.ac\/wp-content\/uploads\/2024\/02\/award-solid.svg&#8217;);||background-repeat:no-repeat;||background-size:100%;||width:35px;||height:50px;||display:block;||position:absolute;||left:-50px;||top:15px;&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p class=\"text-lg md:font-semibold text-start w-3\/4\">Oferta experimental de 24 horas por apenas 0,50 euros<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;|75px||75px|false|true&#8221; custom_padding_tablet=&#8221;30px|50px||50px|false|true&#8221; custom_padding_phone=&#8221;30px|50px||50px|false|true&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text content_tablet=&#8221;<\/p>\n<p class=\"%22text-lg\" md:font-semibold text-start w-34%22>Abonnement mensuel disponible<\/p>\n<p>&#8221; content_phone=&#8221;<\/p>\n<p class=\"%22text-lg\" md:font-semibold text-start w-34%22>Abonnement mensuel disponible<\/p>\n<p>&#8221; content_last_edited=&#8221;on|tablet&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|600|||||||&#8221; text_font_size=&#8221;19px&#8221; custom_padding_tablet=&#8221;10px||||false|false&#8221; custom_padding_phone=&#8221;10px||||false|false&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; custom_css_before=&#8221;content:%22%22;||background:url(&#8216;https:\/\/talkto.ac\/wp-content\/uploads\/2023\/09\/Groupe-273.svg&#8217;);||background-repeat:no-repeat;||background-size:100%;||width:35px;||height:50px;||display:block;||position:absolute;||left:-50px;||top:15px;&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p class=\"text-lg md:font-semibold text-start w-3\/4\">Assinatura<br \/>mensal<br \/>dispon\u00edvel em<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>","protected":false},"excerpt":{"rendered":"<p>L&#8217;entrepriseNos valeurs reposent sur la qualit\u00e9, la pr\u00e9cision et la confiance. Chacun de nos tests de langue est minutieusement con\u00e7u par une \u00e9quipe d&#8217;experts linguistiques qualifi\u00e9s. Nous veillons \u00e0 ce que nos tests \u00e9valuent de mani\u00e8re approfondie les diff\u00e9rentes comp\u00e9tences linguistiques : Compr\u00e9hension \u00e9crite Compr\u00e9hension orale Grammaire Vocabulaire Expression \u00e9crite Vous pouvez \u00eatre assur\u00e9(e) que [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:divi\/placeholder \/-->","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"class_list":["post-24","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/talkto.ac\/pt\/wp-json\/wp\/v2\/pages\/24","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/talkto.ac\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/talkto.ac\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/talkto.ac\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/talkto.ac\/pt\/wp-json\/wp\/v2\/comments?post=24"}],"version-history":[{"count":82,"href":"https:\/\/talkto.ac\/pt\/wp-json\/wp\/v2\/pages\/24\/revisions"}],"predecessor-version":[{"id":3681,"href":"https:\/\/talkto.ac\/pt\/wp-json\/wp\/v2\/pages\/24\/revisions\/3681"}],"wp:attachment":[{"href":"https:\/\/talkto.ac\/pt\/wp-json\/wp\/v2\/media?parent=24"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}